{"id":14118,"date":"2020-10-23T07:10:19","date_gmt":"2020-10-23T05:10:19","guid":{"rendered":"https:\/\/relaxation-naturiste-paris.fr\/?p=14118"},"modified":"2022-02-03T12:33:31","modified_gmt":"2022-02-03T11:33:31","slug":"un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales","status":"publish","type":"post","link":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/2020\/10\/23\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\/","title":{"rendered":"Un massage ayurv\u00e9dique pour \u00e9quilibrer vos \u00e9nergies vitales"},"content":{"rendered":"<p style=\"text-align: justify;\">La m\u00e9decine traditionnelle indienne rassemble plusieurs pratiques comme le massage ayurv\u00e9dique ou l\u2019aromath\u00e9rapie. Elle repose surtout sur l\u2019ayurveda contribuant \u00e0 entretenir un bon \u00e9quilibre entre le corps et l\u2019esprit. Aussi le massage ayurv\u00e9dique vise \u00e0 vous offrir une bonne hygi\u00e8ne de vie. Comme il s\u2019agit d\u2019un outil de bien-\u00eatre, il se pratique sur tout le monde, y compris sur les enfants. N\u00e9anmoins, il est \u00e0 \u00e9viter chez les personnes souffrant d\u2019infections cutan\u00e9es, de fractures, d\u2019enflure ou de d\u00e9chirure. Il faut \u00e9galement faire attention avec sa pratique en cas de fi\u00e8vres, de probl\u00e8mes cardiaques et apr\u00e8s une chirurgie.<\/p>\n<h2>Quels sont les fondements de cette pratique\u00a0?<\/h2>\n<p style=\"text-align: justify;\">Selon la <strong>pratique indienne<\/strong>, cinq \u00e9l\u00e9ments sont pr\u00e9sents dans la nature\u00a0: l\u2019eau, l\u2019air, la terre, le feu et l\u2019espace. Ces derniers existent \u00e9galement dans l\u2019homme et constituent trois types de doshas\u00a0: pittan kapha et vata. Ces doshas \u00e9quivalent aux humeurs biologiques. Ils doivent \u00eatre en symbiose sinon vous risquez un d\u00e9s\u00e9quilibre ou une maladie. Le <strong><a href=\"https:\/\/www.eden-sensation-massage.fr\/massage-ayurvedique\">massage ayurv\u00e9dique<\/a><\/strong> vise alors \u00e0 maintenir l\u2019\u00e9quilibre de ces doshas. Pratiqu\u00e9 avec de l\u2019huile, il touche les centres \u00e9nerg\u00e9tiques dans le corps et cherche \u00e0 <strong>\u00e9liminer le stress<\/strong>.<\/p>\n<h2>Quels sont ses bienfaits pour le corps et pour l\u2019esprit\u00a0?<\/h2>\n<p style=\"text-align: justify;\">Si le massage ayurv\u00e9dique n\u2019est pas r\u00e9ellement un <strong>traitement th\u00e9rapeutique<\/strong>, il offre n\u00e9anmoins de nombreux bienfaits pour le corps. En g\u00e9n\u00e9ral, en fonction des techniques utilis\u00e9es\u00a0:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Il vous aide \u00e0 vous d\u00e9barrasser de toutes vos toxines\u00a0engendr\u00e9es suite \u00e0 une mauvaise alimentation ou une mauvaise habitude ;<\/li>\n<li>Il renforce vos d\u00e9fenses immunitaires, et vous permet de pr\u00e9venir certains maux\u00a0;<\/li>\n<li>Il participe \u00e0 la bonne circulation du sang dans votre corps\u00a0et vous d\u00e9barrasse de vos diff\u00e9rentes tensions nerveuses ;<\/li>\n<li>En tant qu\u2019outil de bien-\u00eatre, il r\u00e9sorbe votre anxi\u00e9t\u00e9 et tous vos stress\u00a0;<\/li>\n<li>Il facilite votre sommeil et am\u00e9liore sa qualit\u00e9\u00a0;<\/li>\n<li>Il renforce vos tissus musculaires\u00a0;<\/li>\n<li>Gr\u00e2ce aux huiles utilis\u00e9es lors de chaque s\u00e9ance, il contribue \u00e0 la bonne sant\u00e9 de votre peau.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Pour b\u00e9n\u00e9ficier des bienfaits de cette pratique, il faut l\u2019accompagner de plusieurs exercices\u00a0: de respiration et de yogas.<\/p>\n<h2>Comment se passe son d\u00e9roulement\u00a0?<\/h2>\n<p style=\"text-align: justify;\">Avant de d\u00e9buter le massage, il faut r\u00e9aliser un <strong>bilan ayurv\u00e9dique<\/strong>. Celui-ci consiste \u00e0 analyser vos doshas et le niveau de d\u00e9s\u00e9quilibre dans votre corps. Cette analyse permet aux praticiens de d\u00e9terminer les techniques appropri\u00e9es pour le massage. De ce fait, ce bilan consiste \u00e0 se renseigner sur vos habitudes au niveau de l\u2019alimentation ou de votre mental. Il cherche \u00e9galement \u00e0 examiner votre pouls ou votre peau et \u00e0 s\u2019informer sur votre pass\u00e9 m\u00e9dical.<\/p>\n<p style=\"text-align: justify;\">Une fois les r\u00e9sultats du bilan obtenus, il est maintenant temps de passer au massage. Il ne faut pas oublier que les techniques utilis\u00e9es varient en fonction du bilan de chaque patient. Pour une personne de type air ou vata, le <strong>massage<\/strong> est plut\u00f4t lent et r\u00e9gulier. Si vous \u00eates de type eau ou kapha, il n\u00e9cessite tr\u00e8s peu d\u2019huile, mais sera tr\u00e8s stimulant. Pour les personnes type feu ou pitta, il est \u00e0 la fois rapide et stimulant. G\u00e9n\u00e9ralement, on r\u00e9alise un <strong>massage ayurv\u00e9dique<\/strong> au sol ou sur une table de massage. Par ailleurs, pour faciliter l\u2019\u00e9vacuation des toxines, vous devez toujours boire beaucoup d\u2019eau apr\u00e8s chaque s\u00e9ance.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La m\u00e9decine traditionnelle indienne rassemble plusieurs pratiques comme le massage ayurv\u00e9dique ou l\u2019aromath\u00e9rapie. Elle repose surtout sur l\u2019ayurveda contribuant \u00e0 entretenir un bon \u00e9quilibre entre le corps et l\u2019esprit. Aussi le massage ayurv\u00e9dique vise \u00e0 vous offrir une bonne hygi\u00e8ne de vie. Comme il s\u2019agit d\u2019un outil de bien-\u00eatre, il se pratique sur tout le [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":14119,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"two_page_speed":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-14118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prenez soin de vos humeurs biologiques gr\u00e2ce \u00e0 un massage ayurv\u00e9dique<\/title>\n<meta name=\"description\" content=\"Un massage ayurv\u00e9dique est une pratique indienne qui vise \u00e0 booster vos d\u00e9fenses immunitaires en \u00e9quilibrant vos doshas. Focus !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/relaxation-naturiste-paris.fr\/index.php\/2020\/10\/23\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prenez soin de vos humeurs biologiques gr\u00e2ce \u00e0 un massage ayurv\u00e9dique\" \/>\n<meta property=\"og:description\" content=\"Un massage ayurv\u00e9dique est une pratique indienne qui vise \u00e0 booster vos d\u00e9fenses immunitaires en \u00e9quilibrant vos doshas. Focus !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/relaxation-naturiste-paris.fr\/index.php\/2020\/10\/23\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\/\" \/>\n<meta property=\"og:site_name\" content=\"Relaxation Naturiste Paris\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-23T05:10:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-03T11:33:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/relaxation-naturiste-paris.fr\/wp-content\/uploads\/2020\/10\/massage-ayurvedique.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adminrelaxation75\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"adminrelaxation75\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/index.php\\\/2020\\\/10\\\/23\\\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/index.php\\\/2020\\\/10\\\/23\\\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\\\/\"},\"author\":{\"name\":\"adminrelaxation75\",\"@id\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/#\\\/schema\\\/person\\\/cb8e3a91f2094d32fb8e8fc7ba23c34f\"},\"headline\":\"Un massage ayurv\u00e9dique pour \u00e9quilibrer vos \u00e9nergies vitales\",\"datePublished\":\"2020-10-23T05:10:19+00:00\",\"dateModified\":\"2022-02-03T11:33:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/index.php\\\/2020\\\/10\\\/23\\\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\\\/\"},\"wordCount\":603,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/index.php\\\/2020\\\/10\\\/23\\\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/massage-ayurvedique.jpg\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/index.php\\\/2020\\\/10\\\/23\\\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/index.php\\\/2020\\\/10\\\/23\\\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\\\/\",\"url\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/index.php\\\/2020\\\/10\\\/23\\\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\\\/\",\"name\":\"Prenez soin de vos humeurs biologiques gr\u00e2ce \u00e0 un massage ayurv\u00e9dique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/index.php\\\/2020\\\/10\\\/23\\\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/index.php\\\/2020\\\/10\\\/23\\\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/massage-ayurvedique.jpg\",\"datePublished\":\"2020-10-23T05:10:19+00:00\",\"dateModified\":\"2022-02-03T11:33:31+00:00\",\"description\":\"Un massage ayurv\u00e9dique est une pratique indienne qui vise \u00e0 booster vos d\u00e9fenses immunitaires en \u00e9quilibrant vos doshas. Focus !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/index.php\\\/2020\\\/10\\\/23\\\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/index.php\\\/2020\\\/10\\\/23\\\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/index.php\\\/2020\\\/10\\\/23\\\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/massage-ayurvedique.jpg\",\"contentUrl\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/massage-ayurvedique.jpg\",\"width\":1280,\"height\":854,\"caption\":\"massage ayurv\u00e9dique\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/index.php\\\/2020\\\/10\\\/23\\\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un massage ayurv\u00e9dique pour \u00e9quilibrer vos \u00e9nergies vitales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/#website\",\"url\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/\",\"name\":\"Relaxation Naturiste Paris\",\"description\":\"Adoptez la Relaxation Naturiste comme style de vie !\",\"publisher\":{\"@id\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/#organization\",\"name\":\"Relaxation Naturiste Paris\",\"url\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/yoga-vs-massage-naturiste.jpg\",\"contentUrl\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/yoga-vs-massage-naturiste.jpg\",\"width\":1000,\"height\":666,\"caption\":\"Relaxation Naturiste Paris\"},\"image\":{\"@id\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/#\\\/schema\\\/person\\\/cb8e3a91f2094d32fb8e8fc7ba23c34f\",\"name\":\"adminrelaxation75\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5feba30eb94fccebe3154f3c6f45b89714465a5074888163ddfdd9f09282513?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5feba30eb94fccebe3154f3c6f45b89714465a5074888163ddfdd9f09282513?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5feba30eb94fccebe3154f3c6f45b89714465a5074888163ddfdd9f09282513?s=96&d=mm&r=g\",\"caption\":\"adminrelaxation75\"},\"sameAs\":[\"adminrelaxation75\"],\"url\":\"https:\\\/\\\/relaxation-naturiste-paris.fr\\\/index.php\\\/author\\\/adminrelaxation75\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prenez soin de vos humeurs biologiques gr\u00e2ce \u00e0 un massage ayurv\u00e9dique","description":"Un massage ayurv\u00e9dique est une pratique indienne qui vise \u00e0 booster vos d\u00e9fenses immunitaires en \u00e9quilibrant vos doshas. Focus !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/2020\/10\/23\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\/","og_locale":"fr_FR","og_type":"article","og_title":"Prenez soin de vos humeurs biologiques gr\u00e2ce \u00e0 un massage ayurv\u00e9dique","og_description":"Un massage ayurv\u00e9dique est une pratique indienne qui vise \u00e0 booster vos d\u00e9fenses immunitaires en \u00e9quilibrant vos doshas. Focus !","og_url":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/2020\/10\/23\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\/","og_site_name":"Relaxation Naturiste Paris","article_published_time":"2020-10-23T05:10:19+00:00","article_modified_time":"2022-02-03T11:33:31+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/relaxation-naturiste-paris.fr\/wp-content\/uploads\/2020\/10\/massage-ayurvedique.jpg","type":"image\/jpeg"}],"author":"adminrelaxation75","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"adminrelaxation75","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/2020\/10\/23\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\/#article","isPartOf":{"@id":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/2020\/10\/23\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\/"},"author":{"name":"adminrelaxation75","@id":"https:\/\/relaxation-naturiste-paris.fr\/#\/schema\/person\/cb8e3a91f2094d32fb8e8fc7ba23c34f"},"headline":"Un massage ayurv\u00e9dique pour \u00e9quilibrer vos \u00e9nergies vitales","datePublished":"2020-10-23T05:10:19+00:00","dateModified":"2022-02-03T11:33:31+00:00","mainEntityOfPage":{"@id":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/2020\/10\/23\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\/"},"wordCount":603,"commentCount":0,"publisher":{"@id":"https:\/\/relaxation-naturiste-paris.fr\/#organization"},"image":{"@id":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/2020\/10\/23\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\/#primaryimage"},"thumbnailUrl":"https:\/\/relaxation-naturiste-paris.fr\/wp-content\/uploads\/2020\/10\/massage-ayurvedique.jpg","inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/relaxation-naturiste-paris.fr\/index.php\/2020\/10\/23\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/2020\/10\/23\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\/","url":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/2020\/10\/23\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\/","name":"Prenez soin de vos humeurs biologiques gr\u00e2ce \u00e0 un massage ayurv\u00e9dique","isPartOf":{"@id":"https:\/\/relaxation-naturiste-paris.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/2020\/10\/23\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\/#primaryimage"},"image":{"@id":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/2020\/10\/23\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\/#primaryimage"},"thumbnailUrl":"https:\/\/relaxation-naturiste-paris.fr\/wp-content\/uploads\/2020\/10\/massage-ayurvedique.jpg","datePublished":"2020-10-23T05:10:19+00:00","dateModified":"2022-02-03T11:33:31+00:00","description":"Un massage ayurv\u00e9dique est une pratique indienne qui vise \u00e0 booster vos d\u00e9fenses immunitaires en \u00e9quilibrant vos doshas. Focus !","breadcrumb":{"@id":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/2020\/10\/23\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/relaxation-naturiste-paris.fr\/index.php\/2020\/10\/23\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/2020\/10\/23\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\/#primaryimage","url":"https:\/\/relaxation-naturiste-paris.fr\/wp-content\/uploads\/2020\/10\/massage-ayurvedique.jpg","contentUrl":"https:\/\/relaxation-naturiste-paris.fr\/wp-content\/uploads\/2020\/10\/massage-ayurvedique.jpg","width":1280,"height":854,"caption":"massage ayurv\u00e9dique"},{"@type":"BreadcrumbList","@id":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/2020\/10\/23\/un-massage-ayurvedique-pour-equilibrer-vos-energies-vitales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/relaxation-naturiste-paris.fr\/"},{"@type":"ListItem","position":2,"name":"Un massage ayurv\u00e9dique pour \u00e9quilibrer vos \u00e9nergies vitales"}]},{"@type":"WebSite","@id":"https:\/\/relaxation-naturiste-paris.fr\/#website","url":"https:\/\/relaxation-naturiste-paris.fr\/","name":"Relaxation Naturiste Paris","description":"Adoptez la Relaxation Naturiste comme style de vie !","publisher":{"@id":"https:\/\/relaxation-naturiste-paris.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/relaxation-naturiste-paris.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/relaxation-naturiste-paris.fr\/#organization","name":"Relaxation Naturiste Paris","url":"https:\/\/relaxation-naturiste-paris.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/relaxation-naturiste-paris.fr\/#\/schema\/logo\/image\/","url":"https:\/\/relaxation-naturiste-paris.fr\/wp-content\/uploads\/2020\/03\/yoga-vs-massage-naturiste.jpg","contentUrl":"https:\/\/relaxation-naturiste-paris.fr\/wp-content\/uploads\/2020\/03\/yoga-vs-massage-naturiste.jpg","width":1000,"height":666,"caption":"Relaxation Naturiste Paris"},"image":{"@id":"https:\/\/relaxation-naturiste-paris.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/relaxation-naturiste-paris.fr\/#\/schema\/person\/cb8e3a91f2094d32fb8e8fc7ba23c34f","name":"adminrelaxation75","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b5feba30eb94fccebe3154f3c6f45b89714465a5074888163ddfdd9f09282513?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b5feba30eb94fccebe3154f3c6f45b89714465a5074888163ddfdd9f09282513?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b5feba30eb94fccebe3154f3c6f45b89714465a5074888163ddfdd9f09282513?s=96&d=mm&r=g","caption":"adminrelaxation75"},"sameAs":["adminrelaxation75"],"url":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/author\/adminrelaxation75\/"}]}},"_links":{"self":[{"href":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/wp-json\/wp\/v2\/posts\/14118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/wp-json\/wp\/v2\/comments?post=14118"}],"version-history":[{"count":2,"href":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/wp-json\/wp\/v2\/posts\/14118\/revisions"}],"predecessor-version":[{"id":14231,"href":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/wp-json\/wp\/v2\/posts\/14118\/revisions\/14231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/wp-json\/wp\/v2\/media\/14119"}],"wp:attachment":[{"href":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/wp-json\/wp\/v2\/media?parent=14118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/wp-json\/wp\/v2\/categories?post=14118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/relaxation-naturiste-paris.fr\/index.php\/wp-json\/wp\/v2\/tags?post=14118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}